{"id":2316,"date":"2018-02-10T16:17:22","date_gmt":"2018-02-10T15:17:22","guid":{"rendered":"http:\/\/scout.fse.it\/coccinelle\/?p=2316"},"modified":"2018-02-10T16:17:22","modified_gmt":"2018-02-10T15:17:22","slug":"canzone-incontro-cda-2018","status":"publish","type":"post","link":"https:\/\/scout.fse.it\/coccinelle\/canzone-incontro-cda-2018\/","title":{"rendered":"Canzone Incontro CDA 2018"},"content":{"rendered":"<h1><strong>TU SEI GES\u00d9!<\/strong><\/h1>\n<div class=\"su-audio\" data-id=\"su_audio_player_6a0499aa750cb\" data-audio=\"http:\/\/scout.fse.it\/mp3\/tuseigesu.mp3\" data-swf=\"https:\/\/scout.fse.it\/coccinelle\/wp-content\/plugins\/shortcodes-ultimate\/vendor\/jplayer\/jplayer.swf\" data-autoplay=\"no\" data-loop=\"no\" style=\"\"><div id=\"su_audio_player_6a0499aa750cb\" class=\"jp-jplayer\"><\/div><div id=\"su_audio_player_6a0499aa750cb_container\" class=\"jp-audio\"><div class=\"jp-type-single\"><div class=\"jp-gui jp-interface\"><div class=\"jp-controls\"><span class=\"jp-play\"><\/span><span class=\"jp-pause\"><\/span><span class=\"jp-stop\"><\/span><span class=\"jp-mute\"><\/span><span class=\"jp-unmute\"><\/span><span class=\"jp-volume-max\"><\/span><\/div><div class=\"jp-progress\"><div class=\"jp-seek-bar\"><div class=\"jp-play-bar\"><\/div><\/div><\/div><div class=\"jp-volume-bar\"><div class=\"jp-volume-bar-value\"><\/div><\/div><div class=\"jp-current-time\"><\/div><div class=\"jp-duration\"><\/div><\/div><div class=\"jp-title\"><\/div><\/div><\/div><\/div>\n<p>Carissime Capo Cerchio,<br \/>\nsiamo ormai giunte alle porte dell\u2019Incontro, ed \u00e8 arrivato il momento di prepararsi a vivere bene questa gioiosa esperienza.<\/p>\n<p><strong><span style=\"text-align: center;\">Il canto, che potete scaricare o ascoltare direttamente dal player, \u00e8 caratterizzato da\u00a0<\/span><span style=\"font-size: small;\">una melodia orecchiabile che le Coccinelle possano imparare con facilit\u00e0.<\/span><\/strong><\/p>\n<p><span style=\"font-size: small;\">Il titolo, TU SEI GESU&#8217;, si riferisce all&#8217;esclamazione dei Discepoli di Emmaus, quando hanno riconosciuto Ges\u00f9 nello spezzare il pane e nel testo si possono trovare tanti riferimenti a quello che andremo a vivere insieme alle nostre coccinelle durante l&#8217;incontro.<\/span><\/p>\n<p><span style=\"font-size: small;\">La prima strofa parla della delusione che attanagliava i due Discepoli in cammino verso Emmaus e della felicit\u00e0 che hanno provato nel riconoscere nel loro compagno di strada il Signore; la seconda strofa, invece, si riferisce all&#8217;attivit\u00e0 di Evangelizzazione cui le Coccinelle saranno chiamate, dopo aver incontrato personalmente il Cristo; nel ritornello, invece, i temi cari alla nostra Branca quali la Gioia e l&#8217;Arcobaleno.<\/span><\/p>\n<p>Buon Volo a tutte<\/p>\n<p>Cristina<\/p>\n<h4><span style=\"font-size: small;\">TESTO\u00a0<\/span><\/h4>\n<p><strong>INTRO: RE SI- SOL MI- LA (2v)<\/strong><\/p>\n<p><strong>SOL\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 RE<\/strong><\/p>\n<p>All\u2019orizzonte il sole sta scendendo<\/p>\n<p><strong>LA\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0SI-\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0LA\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><\/p>\n<p>come la nostra speranza nel domani.<\/p>\n<p><strong>SOL \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0RE<\/strong><\/p>\n<p>Ma ecco, un uomo si avvicina nel cammino:<\/p>\n<p><strong>LA\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SI- LA <\/strong><\/p>\n<p>ci parla di Ges\u00f9.<\/p>\n<p><strong>MI-\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SI-<\/strong><\/p>\n<p>Resta con noi, la notte sta arrivando;<\/p>\n<p><strong>MI-\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SOL\u00a0 LA<\/strong><\/p>\n<p>io ti conosco: tu sei Ges\u00f9!<\/p>\n<p><strong>\u00a0\u00a0\u00a0 RE\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SI-\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SOL MI-\u00a0\u00a0\u00a0\u00a0\u00a0 LA<\/strong><\/p>\n<p>Signore del cielo, la luce \u00a0nelle difficolt\u00e0;<\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0 RE\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SI-\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SOL\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 MI-\u00a0 \u00a0LA<\/strong><\/p>\n<p>un dono d\u2019amore, nel mondo la Gioia trionfer\u00e0.<\/p>\n<p><strong>SOL\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 RE<\/strong><\/p>\n<p>Oh Coccinella ascoltati nel cuore,<\/p>\n<p><strong>LA\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SI-\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 LA<\/strong><\/p>\n<p>perch\u00e9 il Signore ti sta chiamando gi\u00e0.<\/p>\n<p><strong>SOL\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 RE<\/strong><\/p>\n<p>E quando incontri qualcuno nel cammino<\/p>\n<p><strong>LA\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SI- LA<\/strong><\/p>\n<p>parlagli di Ges\u00f9.<\/p>\n<p><strong>MI-\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SI-<\/strong><\/p>\n<p>Presta attenzione ai suoi insegnamenti,<\/p>\n<p><strong>MI-\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0SOL LA\u00a0\u00a0\u00a0 <\/strong><\/p>\n<p>se li conosci diventerai:<\/p>\n<p><strong>RE\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0SI-\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SOL MI-\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 LA<\/strong><\/p>\n<p>un luminoso mattino \u00a0\u00a0per chi \u00e8 in difficolt\u00e0,<\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0 RE\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SI-\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SOL\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 MI-\u00a0 \u00a0LA<\/strong><\/p>\n<p>un dono d\u2019amore, nel mondo la Gioia trionfer\u00e0;<\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0 RE\u00a0\u00a0\u00a0\u00a0 SI-\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SOL\u00a0\u00a0\u00a0 MI-\u00a0\u00a0\u00a0\u00a0\u00a0 LA<\/strong><\/p>\n<p>un arcobaleno nel cielo le nubi colorer\u00e0;<\/p>\n<p><strong>RE\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SI-\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SOL\u00a0\u00a0 MI-\u00a0 LA\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SOL<\/strong><\/p>\n<p>dipingeremo il sereno la notte non scender\u00e0.<\/p>\n<a href=\"https:\/\/scout.fse.it\/coccinelle\/wp-content\/uploads\/2018\/02\/canto.pdf\" class=\"su-button su-button-style-default\" style=\"color:#333333;background-color:#ffcc00;border-color:#cca400;border-radius:7px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#333333;padding:7px 20px;font-size:16px;line-height:24px;border-color:#ffdc4d;border-radius:7px;text-shadow:none\"><i class=\"sui sui-print\" style=\"font-size:16px;color:#333333\"><\/i> TU SEI GESU&#8217; TESTO<small style=\"padding-bottom:7px;color:#333333\">Canto Incontro CDA 2018 PDF<\/small><\/span><\/a> <a href=\"http:\/\/scout.fse.it\/mp3\/tuseigesu.mp3\" class=\"su-button su-button-style-default\" style=\"color:#333333;background-color:#ffcc00;border-color:#cca400;border-radius:7px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#333333;padding:7px 20px;font-size:16px;line-height:24px;border-color:#ffdc4d;border-radius:7px;text-shadow:none\"><i class=\"sui sui-print\" style=\"font-size:16px;color:#333333\"><\/i> TU SEI GESU&#8217; CANTO<small style=\"padding-bottom:7px;color:#333333\">Canto Incontro CDA 2018 MP3<\/small><\/span><\/a><a href=\"https:\/\/scout.fse.it\/coccinelle\/wp-content\/uploads\/2018\/02\/canto-incda.pdf\" class=\"su-button su-button-style-default\" style=\"color:#333333;background-color:#ffcc00;border-color:#cca400;border-radius:7px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#333333;padding:7px 20px;font-size:16px;line-height:24px;border-color:#ffdc4d;border-radius:7px;text-shadow:none\"><i class=\"sui sui-print\" style=\"font-size:16px;color:#333333\"><\/i> TU SEI GESU&#8217; TESTO VERSIONE STAMPABILE<small style=\"padding-bottom:7px;color:#333333\">Canto Incontro CDA 2018 STAMPABILE<\/small><\/span><\/a>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TU SEI GES\u00d9! Carissime Capo Cerchio, siamo ormai giunte alle porte dell\u2019Incontro, ed \u00e8 arrivato il momento di prepararsi a vivere bene questa gioiosa esperienza. Il canto, che potete scaricare o ascoltare direttamente dal player, \u00e8 caratterizzato da\u00a0una melodia orecchiabile che le Coccinelle possano imparare con facilit\u00e0. Il titolo, TU SEI GESU&#8217;, si riferisce all&#8217;esclamazione [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[724,725,716],"tags":[],"class_list":["post-2316","post","type-post","status-publish","format-standard","hentry","category-canti","category-canti-eventi-cs","category-voliamo-insieme"],"_links":{"self":[{"href":"https:\/\/scout.fse.it\/coccinelle\/wp-json\/wp\/v2\/posts\/2316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scout.fse.it\/coccinelle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/scout.fse.it\/coccinelle\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/scout.fse.it\/coccinelle\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/scout.fse.it\/coccinelle\/wp-json\/wp\/v2\/comments?post=2316"}],"version-history":[{"count":0,"href":"https:\/\/scout.fse.it\/coccinelle\/wp-json\/wp\/v2\/posts\/2316\/revisions"}],"wp:attachment":[{"href":"https:\/\/scout.fse.it\/coccinelle\/wp-json\/wp\/v2\/media?parent=2316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/scout.fse.it\/coccinelle\/wp-json\/wp\/v2\/categories?post=2316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/scout.fse.it\/coccinelle\/wp-json\/wp\/v2\/tags?post=2316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}